{"id":2319,"date":"2022-11-07T15:35:14","date_gmt":"2022-11-07T15:35:14","guid":{"rendered":"https:\/\/exceltic.com\/?p=2319"},"modified":"2023-01-02T10:52:18","modified_gmt":"2023-01-02T10:52:18","slug":"niedriger-code","status":"publish","type":"post","link":"https:\/\/exceltic.serquo.com\/de\/low-code\/","title":{"rendered":"Low Code: Vorteile und Anwendungen"},"content":{"rendered":"<p class=\"has-primary-color has-text-color has-large-font-size wp-block-paragraph\">Was ist Low Code?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Low Code bezeichnet die Entwicklung von Anwendungen, f\u00fcr die keine Programmierkenntnisse erforderlich sind, d. h. es handelt sich um eine <a href=\"https:\/\/exceltic.com\/desarrollo-software\/\">Software-Entwicklung<\/a> die nur wenig oder gar keine Kodierung zur Erstellung von Anwendungen und Prozessen erfordert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erreicht wird dies durch die Verwendung visueller Schnittstellen mit einfacher Logik und Drag &amp; Drop-Funktionen, die dem Benutzer Autonomie geben, anstatt sich f\u00fcr komplexere Programmiersprachen zu entscheiden.<\/p>\n\n\n\n<p class=\"has-primary-color has-text-color has-large-font-size wp-block-paragraph\">Was sind die Vorteile?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Geschwindigkeit: <\/strong>Dank der intuitiven Benutzeroberfl\u00e4che mit vorgefertigten Vorlagen wird die Entwicklungszeit exponentiell verk\u00fcrzt, da sie die Agilit\u00e4t f\u00f6rdert.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Kollaborativ:<\/strong> Verbesserte Lesbarkeit des Codes erm\u00f6glicht es jedem, den Status des Projekts zu kennen und sich an der Entscheidungsfindung zu beteiligen<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Erweiterung: <\/strong>Es ist m\u00f6glich, die L\u00f6sung in bestehende Systeme zu integrieren, was den Entwicklern die M\u00f6glichkeit gibt, Projekte auf andere Abteilungen als die IT-Abteilung auszuweiten.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Kostensenkung: <\/strong>Eine k\u00fcrzere Entwicklungszeit und ein einfacheres Projektmanagement f\u00fchren zu einer Senkung der Projektkosten.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Skalierbar:<\/strong> Es \u00fcberbr\u00fcckt die L\u00fccke zwischen Entwicklung und Produktion. Tats\u00e4chlich k\u00f6nnen Module leicht erstellt werden, um die Funktionalit\u00e4t einer bestehenden Software zu erweitern.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Qualit\u00e4t des Codes:<\/strong> Manchmal erfordern Projekte sehr kurze Lieferzeiten, was dazu f\u00fchrt, dass die Entwickler weniger auf die Qualit\u00e4t des Codes achten, was sich letztlich auf die Benutzerfreundlichkeit, Leistung und Verf\u00fcgbarkeit der Entwicklungen auswirkt. Deshalb garantiert Low Code die besten Praktiken in k\u00fcrzester Zeit.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sicherheit:<\/strong> Die Entwicklung mit Low Code folgt den neuesten Industriestandards f\u00fcr Codesicherheit und Datenintegrit\u00e4t.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-primary-color has-text-color has-large-font-size wp-block-paragraph\">Welche Arten von Low-Code-Plattformen gibt es?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es gibt 3 Haupttypen von Plattformen, die Low Code verwenden, um die Entwicklung zu erleichtern:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>BPM oder Gesch\u00e4ftsprozessmanagement. <\/strong>BPMs sind integrale Gesch\u00e4ftsprozessmanagement-Plattformen, die Low-Code-Funktionalit\u00e4ten haben, aber auf Gesch\u00e4ftsprozesse ausgerichtet sind und zus\u00e4tzliche technische Entwicklungen oder Erg\u00e4nzungen erfordern, um andere Bereiche abzudecken. Beispiel: Systeme, IT-Wartung.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Die <strong>produktorientierte Plattformen<\/strong> sind L\u00f6sungen, die auf die Unterst\u00fctzung einer bestehenden Plattform ausgerichtet sind. Sie zeichnen sich dadurch aus, dass sie dem Unternehmen oder dem IT-Endnutzer die M\u00f6glichkeit bieten, eigene L\u00f6sungen direkt auf der Plattform zu entwickeln, allerdings mit dem Nachteil, dass sie nicht auf andere Plattformen exportiert werden k\u00f6nnen.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>All-in-one-Plattformen. <\/strong>Diese Plattformen sind agnostisch und erm\u00f6glichen die Entwicklung von Multi-Experience-Anwendungen f\u00fcr jeden Kanal, jedes Ger\u00e4t, online, offline, intelligent und vernetzt.  Sie erm\u00f6glichen die Integration von Daten und Logik aus beliebigen Datenquellen, Systemen oder Diensten.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-primary-color has-text-color has-large-font-size wp-block-paragraph\">Garner Quadrant Leader: MENDIX<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.mendix.com\/\">Mendix <\/a>ist eine \"All-in-One\"-Plattform, weil sie eine der schnellsten und einfachsten M\u00f6glichkeiten ist, Anwendungen zu erstellen, zu integrieren und zu erweitern. Sie erstellt Anwendungen 10 Mal schneller und mit 70% weniger Ressourcen, so dass Experten in jedem Bereich ihren Beitrag leisten k\u00f6nnen, w\u00e4hrend die IT-Abteilung die Kontrolle beh\u00e4lt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durch einen hybriden oder Multi-Cloud-Einsatz bringt Mendix Low Code f\u00fcr alle Softwareprobleme:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Intelligente Automatisierung (Arbeitsablauf)<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Multi-experience Entwicklung (mobil)<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Datenintegration (Datendrehscheibe)<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>K\u00fcnstliche Intelligenz-unterst\u00fctzte Entwicklung<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vorteile von Mendix:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Offline-Entwicklung<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cloud Agnostiker<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cloud Narrative Architektur<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Entwicklung mobiler Anwendungen<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vor-Ort- und Cloud-Bereitstellung<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Automatisierung mit UiPath<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Exceltic ist <strong>offizieller Partner<\/strong>bietet Low-Code-Dienste f\u00fcr Spanien und Portugal an. <strong>Wenn Sie mehr wissen wollen, laden Sie die kostenlose Version herunter! <\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/signup.mendix.com\/link\/signup\/?source=google&amp;medium=organic\" style=\"border-radius:100px\">JETZT HERUNTERLADEN!<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Low Code, ein Softwareentwicklungsansatz, der darauf abzielt, Anwendungen auf einfache Weise \u00fcber eine intuitive grafische Oberfl\u00e4che zu erstellen.<\/p>","protected":false},"author":1,"featured_media":2323,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-partners"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Low Code: Ventajas y aplicaciones<\/title>\n<meta name=\"description\" content=\"Low Code, un enfoque de desarrollo de software destinado a crear aplicaciones de manera sencilla a trav\u00e9s de una interfaz gr\u00e1fica intuitiva.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exceltic.serquo.com\/de\/niedriger-code\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Low Code: Ventajas y aplicaciones\" \/>\n<meta property=\"og:description\" content=\"Low Code, un enfoque de desarrollo de software destinado a crear aplicaciones de manera sencilla a trav\u00e9s de una interfaz gr\u00e1fica intuitiva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exceltic.serquo.com\/de\/niedriger-code\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/exceltic\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-07T15:35:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-02T10:52:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2022\/11\/Lowcode-min-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1449\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Serquo Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@exceltic\" \/>\n<meta name=\"twitter:site\" content=\"@exceltic\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Serquo Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/low-code\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/low-code\\\/\"},\"author\":{\"name\":\"Serquo Admin\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/#\\\/schema\\\/person\\\/aa4f97f58379cc64179590f276472ad5\"},\"headline\":\"Low Code: Ventajas y aplicaciones\",\"datePublished\":\"2022-11-07T15:35:14+00:00\",\"dateModified\":\"2023-01-02T10:52:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/low-code\\\/\"},\"wordCount\":620,\"image\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/low-code\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exceltic.serquo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Lowcode-min-scaled.webp\",\"articleSection\":[\"Partners\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/low-code\\\/\",\"url\":\"https:\\\/\\\/exceltic.serquo.com\\\/low-code\\\/\",\"name\":\"Low Code: Ventajas y aplicaciones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/low-code\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/low-code\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exceltic.serquo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Lowcode-min-scaled.webp\",\"datePublished\":\"2022-11-07T15:35:14+00:00\",\"dateModified\":\"2023-01-02T10:52:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/#\\\/schema\\\/person\\\/aa4f97f58379cc64179590f276472ad5\"},\"description\":\"Low Code, un enfoque de desarrollo de software destinado a crear aplicaciones de manera sencilla a trav\u00e9s de una interfaz gr\u00e1fica intuitiva.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/low-code\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exceltic.serquo.com\\\/low-code\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/low-code\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exceltic.serquo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Lowcode-min-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/exceltic.serquo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Lowcode-min-scaled.webp\",\"width\":2560,\"height\":1449,\"caption\":\"Low Code\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/low-code\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exceltic.serquo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Low Code: Ventajas y aplicaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/#website\",\"url\":\"https:\\\/\\\/exceltic.serquo.com\\\/\",\"name\":\"\",\"description\":\"Ingenier\u00eda y Consultor\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exceltic.serquo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/#\\\/schema\\\/person\\\/aa4f97f58379cc64179590f276472ad5\",\"name\":\"Serquo Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c335bd9da7b1e9a671364c54e17ba39cb4a646b8eb953383973649c257b1fe49?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c335bd9da7b1e9a671364c54e17ba39cb4a646b8eb953383973649c257b1fe49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c335bd9da7b1e9a671364c54e17ba39cb4a646b8eb953383973649c257b1fe49?s=96&d=mm&r=g\",\"caption\":\"Serquo Admin\"},\"url\":\"https:\\\/\\\/exceltic.serquo.com\\\/de\\\/author\\\/serquo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Low Code: Vorteile und Anwendungen","description":"Low Code, ein Softwareentwicklungsansatz, der darauf abzielt, Anwendungen auf einfache Weise \u00fcber eine intuitive grafische Oberfl\u00e4che zu erstellen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exceltic.serquo.com\/de\/niedriger-code\/","og_locale":"de_DE","og_type":"article","og_title":"Low Code: Ventajas y aplicaciones","og_description":"Low Code, un enfoque de desarrollo de software destinado a crear aplicaciones de manera sencilla a trav\u00e9s de una interfaz gr\u00e1fica intuitiva.","og_url":"https:\/\/exceltic.serquo.com\/de\/niedriger-code\/","article_publisher":"https:\/\/www.facebook.com\/exceltic\/","article_published_time":"2022-11-07T15:35:14+00:00","article_modified_time":"2023-01-02T10:52:18+00:00","og_image":[{"width":2560,"height":1449,"url":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2022\/11\/Lowcode-min-scaled.webp","type":"image\/webp"}],"author":"Serquo Admin","twitter_card":"summary_large_image","twitter_creator":"@exceltic","twitter_site":"@exceltic","twitter_misc":{"Geschrieben von":"Serquo Admin","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exceltic.serquo.com\/low-code\/#article","isPartOf":{"@id":"https:\/\/exceltic.serquo.com\/low-code\/"},"author":{"name":"Serquo Admin","@id":"https:\/\/exceltic.serquo.com\/#\/schema\/person\/aa4f97f58379cc64179590f276472ad5"},"headline":"Low Code: Ventajas y aplicaciones","datePublished":"2022-11-07T15:35:14+00:00","dateModified":"2023-01-02T10:52:18+00:00","mainEntityOfPage":{"@id":"https:\/\/exceltic.serquo.com\/low-code\/"},"wordCount":620,"image":{"@id":"https:\/\/exceltic.serquo.com\/low-code\/#primaryimage"},"thumbnailUrl":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2022\/11\/Lowcode-min-scaled.webp","articleSection":["Partners"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/exceltic.serquo.com\/low-code\/","url":"https:\/\/exceltic.serquo.com\/low-code\/","name":"Low Code: Vorteile und Anwendungen","isPartOf":{"@id":"https:\/\/exceltic.serquo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exceltic.serquo.com\/low-code\/#primaryimage"},"image":{"@id":"https:\/\/exceltic.serquo.com\/low-code\/#primaryimage"},"thumbnailUrl":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2022\/11\/Lowcode-min-scaled.webp","datePublished":"2022-11-07T15:35:14+00:00","dateModified":"2023-01-02T10:52:18+00:00","author":{"@id":"https:\/\/exceltic.serquo.com\/#\/schema\/person\/aa4f97f58379cc64179590f276472ad5"},"description":"Low Code, ein Softwareentwicklungsansatz, der darauf abzielt, Anwendungen auf einfache Weise \u00fcber eine intuitive grafische Oberfl\u00e4che zu erstellen.","breadcrumb":{"@id":"https:\/\/exceltic.serquo.com\/low-code\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exceltic.serquo.com\/low-code\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/exceltic.serquo.com\/low-code\/#primaryimage","url":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2022\/11\/Lowcode-min-scaled.webp","contentUrl":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2022\/11\/Lowcode-min-scaled.webp","width":2560,"height":1449,"caption":"Low Code"},{"@type":"BreadcrumbList","@id":"https:\/\/exceltic.serquo.com\/low-code\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exceltic.serquo.com\/"},{"@type":"ListItem","position":2,"name":"Low Code: Ventajas y aplicaciones"}]},{"@type":"WebSite","@id":"https:\/\/exceltic.serquo.com\/#website","url":"https:\/\/exceltic.serquo.com\/","name":"","description":"Engineering und Beratung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exceltic.serquo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/exceltic.serquo.com\/#\/schema\/person\/aa4f97f58379cc64179590f276472ad5","name":"Serquo Verwaltung","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c335bd9da7b1e9a671364c54e17ba39cb4a646b8eb953383973649c257b1fe49?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c335bd9da7b1e9a671364c54e17ba39cb4a646b8eb953383973649c257b1fe49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c335bd9da7b1e9a671364c54e17ba39cb4a646b8eb953383973649c257b1fe49?s=96&d=mm&r=g","caption":"Serquo Admin"},"url":"https:\/\/exceltic.serquo.com\/de\/author\/serquo\/"}]}},"_links":{"self":[{"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/posts\/2319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/comments?post=2319"}],"version-history":[{"count":10,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/posts\/2319\/revisions"}],"predecessor-version":[{"id":2427,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/posts\/2319\/revisions\/2427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/media\/2323"}],"wp:attachment":[{"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/media?parent=2319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/categories?post=2319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/tags?post=2319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}