{"id":2878,"date":"2024-10-18T09:25:33","date_gmt":"2024-10-18T07:25:33","guid":{"rendered":"https:\/\/exceltic.com\/?p=2878"},"modified":"2026-03-19T13:29:07","modified_gmt":"2026-03-19T12:29:07","slug":"unternehmen-fur-kunstliche-intelligenz","status":"publish","type":"post","link":"https:\/\/exceltic.serquo.com\/de\/impacto-inteligencia-artificial-empresa\/","title":{"rendered":"Exceltic organisiert einen Vortrag \u00fcber die Auswirkungen der k\u00fcnstlichen Intelligenz mit Jon Hernandez"},"content":{"rendered":"<p class=\"has-medium-font-size wp-block-paragraph\">Wir freuen uns, eine neue interne Veranstaltung ank\u00fcndigen zu k\u00f6nnen, an der folgende Personen teilnehmen werden <strong><a href=\"https:\/\/www.jonhernandez.education\/ia\">Jon Hernandez<\/a><\/strong>Das Projekt wird von dem renommierten Experten f\u00fcr k\u00fcnstliche Intelligenz durchgef\u00fchrt, der sich mit den wichtigsten Herausforderungen und Fortschritten in dieser Technologie befasst hat.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Die Veranstaltung, die im Rahmen der <a href=\"https:\/\/sanblasdigital.es\/\">San Blas Digital | Arbeitsagentur der Stadtverwaltung von Madrid<\/a>wird einen Vortrag mit dem Titel <strong>\"Die Revolution der k\u00fcnstlichen Intelligenz: Welle oder Tsunami?\"<\/strong>Jon Hern\u00e1ndez wird zentrale Fragen wie die ethischen Herausforderungen der k\u00fcnstlichen Intelligenz und ihre Auswirkungen auf Gesellschaft und Besch\u00e4ftigung ansprechen. Eines der Hauptthemen wird die Entwicklung der KI in der Wirtschaft sein, wobei er aufzeigen wird, wie diese Technologie die Arbeitsdynamik neu definiert und ihren direkten Einfluss auf die Automatisierung von Prozessen und die Entscheidungsfindung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-tertiary-color has-text-color has-link-color has-large-font-size wp-elements-6459065675161d415fb615a206561ff4\"><strong>Jon Hern\u00e1ndez \u00fcber die bahnbrechenden Auswirkungen der KI<\/strong><\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">In j\u00fcngsten \u00c4u\u00dferungen gegen\u00fcber Medienvertretern wie <a href=\"https:\/\/www.diariodeleon.es\/leon\/240709\/1574719\/ia-te-despedira-hara-alguien-utilizandola.html\">Tageszeitung von Le\u00f3n<\/a> y<a href=\"https:\/\/lavozdeibiza.com\/actualidad\/2024\/05\/26\/con-la-inteligencia-artificial-estamos-superando-el-eslabon-del-homo-sapiens-aunque-sea-sintetico-en-lugar-de-organico\/\"> La Voz de Ibiza<\/a>Jon Hern\u00e1ndez hat vor dem disruptiven Potenzial der k\u00fcnstlichen Intelligenz gewarnt. <strong>\"KI wird uns nicht nur dabei helfen, Prozesse zu optimieren, sondern sie ver\u00e4ndert unser Wesen als Gesellschaft\".<\/strong>Er betonte, dass wir vor einem \u00dcbergang stehen, den einige Experten mit der Verabschiedung des <strong>Vom Homo sapiens zum \"Homo syntheticus\".<\/strong>. In seinem Vortrag wird Jon darauf eingehen, wie diese Ver\u00e4nderungen sowohl Chancen als auch Herausforderungen mit sich bringen k\u00f6nnen, von der Steigerung der Produktionseffizienz bis zur Verdr\u00e4ngung von Arbeitskr\u00e4ften durch Automatisierung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-tertiary-color has-text-color has-link-color has-large-font-size wp-elements-a4cb0a9de78a95c4bf9704237b30d1ce\"><strong>Was ist von der Zukunft der k\u00fcnstlichen Intelligenz in der Wirtschaft zu erwarten?<\/strong><\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Eines der umstrittensten Themen wird auch die Zukunft fortgeschrittener KI-Modelle sein, wie z. B. <strong>ChatGPT-5<\/strong>Hernandez hat seine Bedenken ge\u00e4u\u00dfert. In einem Interview mit <a href=\"https:\/\/www.diariocritico.com\/tecnologias\/experto-en-inteligencia-artificial-alerta-chatgpt-5-da-miedo\">Kritische Zeitschrift<\/a>Er betonte, dass <strong>\"ChatGPT-5 ist be\u00e4ngstigend\".<\/strong>und verweist auf die ethischen Implikationen und die autonome F\u00e4higkeit dieser Modelle, Entscheidungen zu treffen, die bisher allein dem Menschen vorbehalten waren.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Diese Veranstaltung ist eine hervorragende Gelegenheit f\u00fcr unser Team, nicht nur einen tieferen Einblick in die Rolle der KI bei der digitalen Transformation zu gewinnen, sondern auch gemeinsam \u00fcber die m\u00f6glichen Richtungen dieser Technologie und ihre Auswirkungen auf das Arbeitsumfeld von Exceltic nachzudenken.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-tertiary-color has-text-color has-link-color has-large-font-size wp-elements-7f3c8518b68f35ab5f82eb0b984f3b64\"><strong>Ein wichtiges Ereignis f\u00fcr die Zukunft der KI bei Exceltic<\/strong><\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Die Sitzung findet in einem pers\u00f6nlichen Format auf der <strong>Escuela de Competencias Digitales San Blas Digital |Agencia para el Empleo del Ayuntamiento de Madrid.<\/strong> Mit Initiativen wie dieser unterstreichen wir unser Engagement f\u00fcr kontinuierliches Lernen und Innovation in unserem Unternehmen.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>\u00dcber Jon Hern\u00e1ndez:<\/strong> Jon Hern\u00e1ndez ist eine Referenz auf dem Gebiet der k\u00fcnstlichen Intelligenz und kann auf eine solide Erfolgsbilanz verweisen, die Forschung und Beratung f\u00fcr Unternehmen in verschiedenen Sektoren umfasst. Seine \u00dcberlegungen zur Zukunft der k\u00fcnstlichen Intelligenz und ihren sozialen Auswirkungen haben ihn in verschiedenen Medien und auf internationalen Konferenzen zu einer ma\u00dfgeblichen Stimme gemacht.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Interessiert an<\/strong>virtuell teilnehmen m\u00f6chten? <\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Gehen Sie direkt zur Veranstaltung unter <a href=\"https:\/\/www.linkedin.com\/events\/larevoluci-ndelaiaconjonhern-nd7252941441637769216\/about\/\">LinkedIn <\/a>oder durch <a href=\"https:\/\/www.youtube.com\/watch?v=vZVxozHGXjo&amp;ab_channel=Exceltic\">YouTube<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Entdecken Sie die Auswirkungen von k\u00fcnstlicher Intelligenz in der Wirtschaft mit Jon Hernandez bei einer Exceltic-Veranstaltung. Erfahren Sie, wie KI die Arbeitsprozesse und die Zukunft der Arbeit ver\u00e4ndert.<\/p>","protected":false},"author":3,"featured_media":2880,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,31],"tags":[],"class_list":["post-2878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-talento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exceltic organiza una charla sobre el impacto de la Inteligencia Artificial con Jon Hern\u00e1ndez -<\/title>\n<meta name=\"description\" content=\"Descubre el impacto de la inteligencia artificial en la empresa con Jon Hern\u00e1ndez en un evento de Exceltic. Aprende c\u00f3mo la IA est\u00e1 transformando los procesos laborales y el futuro del trabajo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exceltic.serquo.com\/de\/unternehmen-fur-kunstliche-intelligenz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exceltic organiza una charla sobre el impacto de la Inteligencia Artificial con Jon Hern\u00e1ndez -\" \/>\n<meta property=\"og:description\" content=\"Descubre el impacto de la inteligencia artificial en la empresa con Jon Hern\u00e1ndez en un evento de Exceltic. Aprende c\u00f3mo la IA est\u00e1 transformando los procesos laborales y el futuro del trabajo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exceltic.serquo.com\/de\/unternehmen-fur-kunstliche-intelligenz\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/exceltic\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-18T07:25:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-19T12:29:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2024\/10\/jon-hernandez-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1547\" \/>\n\t<meta property=\"og:image:height\" content=\"871\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@exceltic\" \/>\n<meta name=\"twitter:site\" content=\"@exceltic\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/impacto-inteligencia-artificial-empresa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/impacto-inteligencia-artificial-empresa\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Exceltic organiza una charla sobre el impacto de la Inteligencia Artificial con Jon Hern\u00e1ndez\",\"datePublished\":\"2024-10-18T07:25:33+00:00\",\"dateModified\":\"2026-03-19T12:29:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/impacto-inteligencia-artificial-empresa\\\/\"},\"wordCount\":532,\"image\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/impacto-inteligencia-artificial-empresa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exceltic.serquo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/jon-hernandez-1.jpg\",\"articleSection\":[\"Eventos\",\"Talento\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/impacto-inteligencia-artificial-empresa\\\/\",\"url\":\"https:\\\/\\\/exceltic.serquo.com\\\/impacto-inteligencia-artificial-empresa\\\/\",\"name\":\"Exceltic organiza una charla sobre el impacto de la Inteligencia Artificial con Jon Hern\u00e1ndez -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/impacto-inteligencia-artificial-empresa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/impacto-inteligencia-artificial-empresa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exceltic.serquo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/jon-hernandez-1.jpg\",\"datePublished\":\"2024-10-18T07:25:33+00:00\",\"dateModified\":\"2026-03-19T12:29:07+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Descubre el impacto de la inteligencia artificial en la empresa con Jon Hern\u00e1ndez en un evento de Exceltic. Aprende c\u00f3mo la IA est\u00e1 transformando los procesos laborales y el futuro del trabajo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/impacto-inteligencia-artificial-empresa\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exceltic.serquo.com\\\/impacto-inteligencia-artificial-empresa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/impacto-inteligencia-artificial-empresa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exceltic.serquo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/jon-hernandez-1.jpg\",\"contentUrl\":\"https:\\\/\\\/exceltic.serquo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/jon-hernandez-1.jpg\",\"width\":1547,\"height\":871,\"caption\":\"Revoluci\u00f3n de la Inteligencia Artificial: \u00bfOla o Tsunami?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/impacto-inteligencia-artificial-empresa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exceltic.serquo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exceltic organiza una charla sobre el impacto de la Inteligencia Artificial con Jon Hern\u00e1ndez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/#website\",\"url\":\"https:\\\/\\\/exceltic.serquo.com\\\/\",\"name\":\"\",\"description\":\"Ingenier\u00eda y Consultor\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exceltic.serquo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/exceltic.serquo.com\\\/de\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exceltic organisiert einen Vortrag \u00fcber die Auswirkungen der k\u00fcnstlichen Intelligenz mit Jon Hernandez -","description":"Entdecken Sie die Auswirkungen von k\u00fcnstlicher Intelligenz in der Wirtschaft mit Jon Hernandez bei einer Exceltic-Veranstaltung. Erfahren Sie, wie KI die Arbeitsprozesse und die Zukunft der Arbeit ver\u00e4ndert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exceltic.serquo.com\/de\/unternehmen-fur-kunstliche-intelligenz\/","og_locale":"de_DE","og_type":"article","og_title":"Exceltic organiza una charla sobre el impacto de la Inteligencia Artificial con Jon Hern\u00e1ndez -","og_description":"Descubre el impacto de la inteligencia artificial en la empresa con Jon Hern\u00e1ndez en un evento de Exceltic. Aprende c\u00f3mo la IA est\u00e1 transformando los procesos laborales y el futuro del trabajo.","og_url":"https:\/\/exceltic.serquo.com\/de\/unternehmen-fur-kunstliche-intelligenz\/","article_publisher":"https:\/\/www.facebook.com\/exceltic\/","article_published_time":"2024-10-18T07:25:33+00:00","article_modified_time":"2026-03-19T12:29:07+00:00","og_image":[{"width":1547,"height":871,"url":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2024\/10\/jon-hernandez-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@exceltic","twitter_site":"@exceltic","twitter_misc":{"Geschrieben von":"","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exceltic.serquo.com\/impacto-inteligencia-artificial-empresa\/#article","isPartOf":{"@id":"https:\/\/exceltic.serquo.com\/impacto-inteligencia-artificial-empresa\/"},"author":{"name":"","@id":""},"headline":"Exceltic organiza una charla sobre el impacto de la Inteligencia Artificial con Jon Hern\u00e1ndez","datePublished":"2024-10-18T07:25:33+00:00","dateModified":"2026-03-19T12:29:07+00:00","mainEntityOfPage":{"@id":"https:\/\/exceltic.serquo.com\/impacto-inteligencia-artificial-empresa\/"},"wordCount":532,"image":{"@id":"https:\/\/exceltic.serquo.com\/impacto-inteligencia-artificial-empresa\/#primaryimage"},"thumbnailUrl":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2024\/10\/jon-hernandez-1.jpg","articleSection":["Eventos","Talento"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/exceltic.serquo.com\/impacto-inteligencia-artificial-empresa\/","url":"https:\/\/exceltic.serquo.com\/impacto-inteligencia-artificial-empresa\/","name":"Exceltic organisiert einen Vortrag \u00fcber die Auswirkungen der k\u00fcnstlichen Intelligenz mit Jon Hernandez -","isPartOf":{"@id":"https:\/\/exceltic.serquo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exceltic.serquo.com\/impacto-inteligencia-artificial-empresa\/#primaryimage"},"image":{"@id":"https:\/\/exceltic.serquo.com\/impacto-inteligencia-artificial-empresa\/#primaryimage"},"thumbnailUrl":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2024\/10\/jon-hernandez-1.jpg","datePublished":"2024-10-18T07:25:33+00:00","dateModified":"2026-03-19T12:29:07+00:00","author":{"@id":""},"description":"Entdecken Sie die Auswirkungen von k\u00fcnstlicher Intelligenz in der Wirtschaft mit Jon Hernandez bei einer Exceltic-Veranstaltung. Erfahren Sie, wie KI die Arbeitsprozesse und die Zukunft der Arbeit ver\u00e4ndert.","breadcrumb":{"@id":"https:\/\/exceltic.serquo.com\/impacto-inteligencia-artificial-empresa\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exceltic.serquo.com\/impacto-inteligencia-artificial-empresa\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/exceltic.serquo.com\/impacto-inteligencia-artificial-empresa\/#primaryimage","url":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2024\/10\/jon-hernandez-1.jpg","contentUrl":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2024\/10\/jon-hernandez-1.jpg","width":1547,"height":871,"caption":"Revoluci\u00f3n de la Inteligencia Artificial: \u00bfOla o Tsunami?"},{"@type":"BreadcrumbList","@id":"https:\/\/exceltic.serquo.com\/impacto-inteligencia-artificial-empresa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exceltic.serquo.com\/"},{"@type":"ListItem","position":2,"name":"Exceltic organiza una charla sobre el impacto de la Inteligencia Artificial con Jon Hern\u00e1ndez"}]},{"@type":"WebSite","@id":"https:\/\/exceltic.serquo.com\/#website","url":"https:\/\/exceltic.serquo.com\/","name":"","description":"Engineering und Beratung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exceltic.serquo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"","url":"https:\/\/exceltic.serquo.com\/de\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/posts\/2878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/comments?post=2878"}],"version-history":[{"count":7,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/posts\/2878\/revisions"}],"predecessor-version":[{"id":3998,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/posts\/2878\/revisions\/3998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/media\/2880"}],"wp:attachment":[{"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/media?parent=2878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/categories?post=2878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exceltic.serquo.com\/de\/wp-json\/wp\/v2\/tags?post=2878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}