{"id":1975,"date":"2022-07-26T08:17:04","date_gmt":"2022-07-26T08:17:04","guid":{"rendered":"https:\/\/exceltic.com\/?p=1975"},"modified":"2022-10-27T07:05:37","modified_gmt":"2022-10-27T07:05:37","slug":"creation-and-automation-of-an-etl-convert-xml-to-a-relational-dataset","status":"publish","type":"post","link":"https:\/\/exceltic.serquo.com\/en\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\/","title":{"rendered":"ETL with Alteryx: Converting XML to a relational dataset"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Cada d\u00eda, <strong>las empresas acumulan una mayor cantidad de documentaci\u00f3n<\/strong> debido al aumento de procesos que pueden gestionarse desde un sistema inform\u00e1tico. Por lo tanto, se produce una descentralizaci\u00f3n a\u00fan mayor en la toma de decisiones basada en datos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan diversos estudios, el 92% de las empresas invierten en almacenamiento, anal\u00edtica e inteligencia artificial para sacar provecho de su informaci\u00f3n. Sin embargo, solo el 19% considera que toman las decisiones estrat\u00e9gicas adecuadas y fundamentadas en datos (<strong>Data Driven companies<\/strong>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El problema<\/strong>, en numerosas ocasiones, reside en la <strong>diversa procedencia de los datos<\/strong>. Estos son recopilados desde diferentes fuentes, ya sea desde un sistema de producci\u00f3n y almacenaje, desde los diferentes departamentos de ventas, o incluso, desde diferentes departamentos financieros y de recursos humanos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, hay que sumar que no todos los datos mantienen el mismo formato (XML, JSON, XLS&#8230;), lo que dificulta a\u00fan m\u00e1s su comparaci\u00f3n. De este modo, surge la necesidad de crear ETLs.<\/p>\n\n\n\n<p class=\"has-primary-color has-text-color has-large-font-size wp-block-paragraph\">\u00bfQU\u00c9 ES UNA ETL?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una <strong>ETL<\/strong>, por sus siglas en ingl\u00e9s (Extract, Transform, Load) surge como una herramienta capaz de <strong>centralizar<\/strong> la informaci\u00f3n, <strong>extraerla<\/strong> de diferentes fuentes, <strong>transformar <\/strong>todos aquellos criterios deseados para su mejor comprensi\u00f3n o eliminaci\u00f3n de erratas y posterior carga a un data warehouse de destino.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos movimientos de datos pueden programarse de forma regular o activarse para que se produzcan peri\u00f3dicamente. Los tipos de proyectos para los que se utilizan las herramientas ETL var\u00edan mucho, ya que estas herramientas est\u00e1n dise\u00f1adas para ser muy flexibles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Algunos proyectos comunes ser\u00edan:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Migraci\u00f3n de datos de aplicaciones de sistemas antiguos a nuevos<\/li><li><a href=\"https:\/\/exceltic.com\/integridad-de-datos\/\">Integraci\u00f3n de datos<\/a> de fusiones y adquisiciones corporativas recientes<\/li><li>Integraci\u00f3n de datos de proveedores y socios externos<\/li><li>Recopilaci\u00f3n de datos de transacciones para que trabajen personas de negocio, lo que com\u00fanmente llamamos Data Marts o Data Warehouses<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que una organizaci\u00f3n se decanta por una ETL, la compa\u00f1\u00eda queda \u00abcasada\u00bb con esa herramienta en espec\u00edfico, ya que, se dise\u00f1ar\u00e1 una gran cantidad de l\u00f3gica en los procesos de movimiento de datos y se convertir\u00e1 en parte vital para administrar su negocio. Por lo tanto, <strong>la compra y el uso de una herramienta ETL es un movimiento muy estrat\u00e9gico<\/strong>, incluso si, para empezar, est\u00e1 destinado a un peque\u00f1o proyecto t\u00e1ctico. <\/p>\n\n\n\n<p class=\"has-primary-color has-text-color has-large-font-size wp-block-paragraph\">\u00bfQU\u00c9 FASES TIENE UNA ETL?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-secondary-color\">Fase de Extracci\u00f3n:<\/mark><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de empresas cuenta con numerosas fuentes de datos y usa un sin fin de herramientas de an\u00e1lisis para producir business intelligence. La extracci\u00f3n consiste en <strong>traer data \u00abcruda\u00bb de diferentes fuentes y transferirla a un repositorio \u00fanico<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Algunos ejemplos de data sources pueden ser:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Sistemas legacy o heredados<\/li><li>Bases de datos relacionales<\/li><li>Archivos XML<\/li><li>Sistemas CRM<\/li><li>Archivos XLS<\/li><li>Aplicaciones de negocio<\/li><li>Herramientas de anal\u00edticas<\/li><li>JSON<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tener fuentes de datos diferentes representa un reto muy importante para las organizaciones, dado que al almacenar informaci\u00f3n de distinta naturaleza, los costes de gobierno del dato y de almacenamiento aumentan significativamente. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adicionalmente, hay ecosistemas que no son compatibles con otras soluciones de forma nativa, lo que dificulta a\u00fan m\u00e1s el entrelazar informaci\u00f3n con diferentes or\u00edgenes y diferentes formatos entre s\u00ed. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-secondary-color\">Fase de Transformaci\u00f3n: <\/mark><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La etapa de limpieza y organizaci\u00f3n es la etapa en la que todos los datos procedentes de m\u00faltiples sistemas de origen<strong> se normalizan y se convierten a un formato de conveniencia<\/strong>, lo que mejora su calidad, su gobierno y su explotaci\u00f3n. Durante esta etapa, los datos pueden someterse a diversas operaciones: limpieza, filtrado, desacople, combinaci\u00f3n, reorganizaci\u00f3n, duplicaci\u00f3n&#8230;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunas de las <strong>principales ventajas<\/strong> de la transformaci\u00f3n autom\u00e1tica frente a la manual es garantizar que se realicen cambios globales en los conjuntos de datos de manera sistem\u00e1tica, por ejemplo, se pueden eliminar los caracteres especiales y cambiar completamente la disposici\u00f3n de los datos una vez completado el proceso de transformaci\u00f3n de datos, se pueden eliminar elementos que se encuentren duplicados, modificar el formato de los campos, suprimir filas y columnas en blanco o que sean redundantes, y mantener \u00fanicamente aquellos datos que sean interesantes almacenar para su posterior explotaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-secondary-color\">Fase de Carga:<\/mark><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras tener esta nueva vista, con una nueva perspectiva, <strong>se deben cargar esos nuevos datos seleccionados en un almac\u00e9n de datos<\/strong>. La carga de una gran cantidad de datos en un data warehouse por ejemplo, facilita el acceso y el uso de la informaci\u00f3n, independientemente de cu\u00e1ntos tipos de datos diferentes hayan pasado por el proceso de ETL.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El resultado es un conjunto limpio de datos, estructurados y correctamente clasificados, que est\u00e1n listos para ser utilizados, lo que ayudar\u00e1 a las organizaciones a tomar decisiones cr\u00edticas de negocio y a realizar an\u00e1lisis posteriores de manera eficaz.<\/p>\n\n\n\n<p class=\"has-primary-color has-text-color has-large-font-size wp-block-paragraph\">\u00bfQU\u00c9 VENTAJAS TIENE UNA ETL?<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Permite un repositorio de datos com\u00fan<\/li><li>Mejora la toma de decisiones<\/li><li>Permite la comparaci\u00f3n de datos de muestra entre el sistema de origen y el de destino&nbsp;<\/li><li>Ayuda a mejorar la productividad, ya que codifica y reutiliza sin necesidad de conocimientos t\u00e9cnicos adicionales. Las ETL ofrecen un contexto hist\u00f3rico profundo para el negocio<\/li><li>Ayuda a identificar patrones y conocimientos significativos<\/li><li>Convierte datos variados en un formato coherente<\/li><li>Ayuda a obtener business intelligence a partir de los datos&nbsp;<\/li><li>Contiene componentes f\u00e1cilmente utilizables&nbsp;<\/li><li>Gestiona sin esfuerzo la compleja transformaci\u00f3n&nbsp;<\/li><li>Ofrece la m\u00e1xima rentabilidad de la inversi\u00f3n, es decir, roi<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de que<strong> estas herramientas se pueden programar con cualquier lenguaje <\/strong>(Java, C, C++, PHP\u2026) est\u00e1n programadas principalmente en Python debido a la gran cantidad de librer\u00edas existentes, y se suelen ejecutar con Apache Spark y PySpark&nbsp;<\/p>\n\n\n\n<p class=\"has-primary-color has-text-color has-large-font-size wp-block-paragraph\">ALTERYX<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, <strong>existe una brecha importante entre los programadores y los analistas de datos<\/strong>, ya que los primeros tienen el conocimiento t\u00e9cnico, para llevarlo a cabo, y los segundos son quien deben \u201cjugar\u201d con los datos para llegar a conclusiones v\u00e1lidas para el desarrollo de negocio. Esto supone una coordinaci\u00f3n y una p\u00e9rdida de eficiencia valorada en millones de \u20ac anuales que puedes calcular gracias a la <a href=\"https:\/\/www.alteryx.com\/es-419\/roi-calculator?utm_source=partner_generated&amp;utm_medium=pn_exceltic_sociedad_limitada&amp;prid=0032R00002Jqz0KQAR&amp;crp=0032R00002Jqz0KQAR&amp;apid=0012R00002DxPTcQAN\">Alteryx APA Platform\u2122<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es por ello que durante los \u00faltimos a\u00f1os, han surgido herramientas <strong>Low code<\/strong> que han revolucionado los procesos ETL, dando potestad a los usuarios finales (Data analysts) de hacer sus propias extracciones, transformaciones y carga de datos para su posterior an\u00e1lisis.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas herramientas van m\u00e1s all\u00e1, dando la posibilidad de aplicar diferentes m\u00f3dulos que permiten el an\u00e1lisis mediante Inteligencia Artificial (machine y Deep learning) y obtener las conclusiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este video mostramos c\u00f3mo en menos de 5 minutos creamos una ETL para la extracci\u00f3n de un set de datos XML y posterior transformaci\u00f3n y carga a una bbdd relacional con nuestra herramienta <strong><a href=\"https:\/\/www.alteryx.com\/es-419\">ALTERYX<\/a><\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Introducci\u00f3n Alteryx ETL: C\u00f3mo transformar un archivo XML en un dataset con estructura relacional\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/odptsREQmtA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alteryx facilita el acceso a datos dispares, el an\u00e1lisis y la ciencia de datos a trav\u00e9s de una plataforma sin c\u00f3digo y amigable con el c\u00f3digo.<\/strong> Permite empoderar a los analistas de negocio para que puedan automatizar sus flujos de anal\u00edticas y de procesos completos en el contexto del resultado comercial deseado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La plataforma cuenta con una interfaz intuitiva que permite arrastrar y soltar bloques que permiten la conectividad con diferentes fuentes de informaci\u00f3n y su posterior transformaci\u00f3n y an\u00e1lisis.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alteryx est\u00e1 presente en todas las \u00e1reas de la empresa:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes has-small-font-size\"><table style=\"border-style:none;border-width:0px\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">RRHH<\/th><th class=\"has-text-align-center\" data-align=\"center\">FINANZAS<\/th><th class=\"has-text-align-center\" data-align=\"center\">MARKETING &amp; VENTAS<\/th><th class=\"has-text-align-center\" data-align=\"center\">OPERACIONES<\/th><th class=\"has-text-align-center\" data-align=\"center\">CADENA DE SUMINISTRO<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Retenci\u00f3n del empleado<\/td><td class=\"has-text-align-center\" data-align=\"center\">Automatizaci\u00f3n de impuestos<\/td><td class=\"has-text-align-center\" data-align=\"center\">Segmentaci\u00f3n<\/td><td class=\"has-text-align-center\" data-align=\"center\">Gesti\u00f3n de incidencias<\/td><td class=\"has-text-align-center\" data-align=\"center\">Previsi\u00f3n de demanda<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">EGS<\/td><td class=\"has-text-align-center\" data-align=\"center\">Auditoria y cumplimiento<\/td><td class=\"has-text-align-center\" data-align=\"center\">Previsi\u00f3n<\/td><td class=\"has-text-align-center\" data-align=\"center\">An\u00e1lisis de tiempo de respuesta<\/td><td class=\"has-text-align-center\" data-align=\"center\">Optimizaci\u00f3n de inventario<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Reclutamiento<\/td><td class=\"has-text-align-center\" data-align=\"center\">Reconciliaci\u00f3n diaria<\/td><td class=\"has-text-align-center\" data-align=\"center\">Clientes 360<\/td><td class=\"has-text-align-center\" data-align=\"center\">An\u00e1lisis del centro de llamadas<\/td><td class=\"has-text-align-center\" data-align=\"center\">Mantenimiento predictivo<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Rendimiento<\/td><td class=\"has-text-align-center\" data-align=\"center\">Planificaci\u00f3n y an\u00e1lisis financiero<\/td><td class=\"has-text-align-center\" data-align=\"center\">Rotaci\u00f3n<\/td><td class=\"has-text-align-center\" data-align=\"center\">Sentimiento del cliente<\/td><td class=\"has-text-align-center\" data-align=\"center\">Planificaci\u00f3n de capacidad<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Gesti\u00f3n<\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-d398a0d5 wp-block-columns-is-layout-flex\" style=\"padding-top:50px;padding-bottom:5px\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"beneficios\">\u00bfQUIERES SABER M\u00c1S?<\/h2>\n\n\n<div class=\"wpforms-container wpforms-container-full wpforms-block contact-us\" id=\"wpforms-1165\"><form id=\"wpforms-form-1165\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"1165\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/posts\/1975\" data-token=\"f1f5393cee8c974d6c31ca8bb44e566f\" data-token-time=\"1784140028\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-1165-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1165-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1165-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Correo electr\u00f3nico\" spellcheck=\"false\" required><\/div><div id=\"wpforms-1165-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1165-field_5\">Asunto <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1165-field_5\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][5]\" placeholder=\"Asunto\" required><\/div><div id=\"wpforms-1165-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1165-field_2\">Mensaje<\/label><textarea id=\"wpforms-1165-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" placeholder=\"Mensaje\" ><\/textarea><\/div><div id=\"wpforms-1165-field_6-container\" class=\"wpforms-field wpforms-field-checkbox boxtransparent\" data-field-id=\"6\"><ul id=\"wpforms-1165-field_6\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-1165-field_6_1\" name=\"wpforms[fields][6][]\" value=\" He le\u00eddo y acepto la pol\u00edtica de privacidad\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1165-field_6_1\">He le\u00eddo y acepto la pol\u00edtica de privacidad <span class=\"wpforms-required-label\">*<\/span><\/label><\/li><\/ul><div class=\"wpforms-field-description wpforms-disclaimer-description\"><b>IMPORTANTE:<\/b> Lea nuestra <a href='https:\/\/exceltic.com\/politica-de-privacidad\/' target='_blank' style=\"color: #e74b10;\" >Pol\u00edtica de Privacidad<\/a> antes de proceder. La informaci\u00f3n que facilite puede contener informaci\u00f3n de car\u00e1cter personal.<\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v2\" ><div class=\"g-recaptcha\" data-sitekey=\"6Lf9t3srAAAAAEstc-76vP4_LAvjdEbLQwgAri5D\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-recaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1165\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/exceltic.serquo.com\/en\/wp-json\/wp\/v2\/posts\/1975\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1165\" class=\"wpforms-submit submit-button\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/exceltic.serquo.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"<p>Extraction from various data sources using our Alteryx tool, transformation of an XML file and automatic loading of the data for easy manipulation.<\/p>","protected":false},"author":1,"featured_media":2008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-partners"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ETL con Alteryx: Convertir XML a un set de datos relacionales<\/title>\n<meta name=\"description\" content=\"ETL en Alteryx de un archivo XML, convirti\u00e9ndolo en un set de datos relacional, para facilitar su posterior consumo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exceltic.serquo.com\/en\/creation-and-automation-of-an-etl-convert-xml-to-a-relational-dataset\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ETL con Alteryx: Convertir XML a un set de datos relacionales\" \/>\n<meta property=\"og:description\" content=\"ETL en Alteryx de un archivo XML, convirti\u00e9ndolo en un set de datos relacional, para facilitar su posterior consumo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exceltic.serquo.com\/en\/creation-and-automation-of-an-etl-convert-xml-to-a-relational-dataset\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/exceltic\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-26T08:17:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-27T07:05:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2022\/07\/ETL-XML-min-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1449\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Serquo Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@exceltic\" \/>\n<meta name=\"twitter:site\" content=\"@exceltic\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Serquo Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\\\/\"},\"author\":{\"name\":\"Serquo Admin\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/#\\\/schema\\\/person\\\/aa4f97f58379cc64179590f276472ad5\"},\"headline\":\"ETL con Alteryx: Convertir XML a un set de datos relacionales\",\"datePublished\":\"2022-07-26T08:17:04+00:00\",\"dateModified\":\"2022-10-27T07:05:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\\\/\"},\"wordCount\":1351,\"image\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exceltic.serquo.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ETL-XML-min-scaled.webp\",\"articleSection\":[\"Partners\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\\\/\",\"url\":\"https:\\\/\\\/exceltic.serquo.com\\\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\\\/\",\"name\":\"ETL con Alteryx: Convertir XML a un set de datos relacionales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exceltic.serquo.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ETL-XML-min-scaled.webp\",\"datePublished\":\"2022-07-26T08:17:04+00:00\",\"dateModified\":\"2022-10-27T07:05:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/#\\\/schema\\\/person\\\/aa4f97f58379cc64179590f276472ad5\"},\"description\":\"ETL en Alteryx de un archivo XML, convirti\u00e9ndolo en un set de datos relacional, para facilitar su posterior consumo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exceltic.serquo.com\\\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exceltic.serquo.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ETL-XML-min-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/exceltic.serquo.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ETL-XML-min-scaled.webp\",\"width\":2560,\"height\":1449,\"caption\":\"ETL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exceltic.serquo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ETL con Alteryx: Convertir XML a un set de datos relacionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/#website\",\"url\":\"https:\\\/\\\/exceltic.serquo.com\\\/\",\"name\":\"\",\"description\":\"Ingenier\u00eda y Consultor\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exceltic.serquo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exceltic.serquo.com\\\/#\\\/schema\\\/person\\\/aa4f97f58379cc64179590f276472ad5\",\"name\":\"Serquo Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c335bd9da7b1e9a671364c54e17ba39cb4a646b8eb953383973649c257b1fe49?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c335bd9da7b1e9a671364c54e17ba39cb4a646b8eb953383973649c257b1fe49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c335bd9da7b1e9a671364c54e17ba39cb4a646b8eb953383973649c257b1fe49?s=96&d=mm&r=g\",\"caption\":\"Serquo Admin\"},\"url\":\"https:\\\/\\\/exceltic.serquo.com\\\/en\\\/author\\\/serquo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ETL with Alteryx: Converting XML to a relational dataset","description":"ETL in Alteryx of an XML file, converting it into a relational dataset, to facilitate its further consumption.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exceltic.serquo.com\/en\/creation-and-automation-of-an-etl-convert-xml-to-a-relational-dataset\/","og_locale":"en_GB","og_type":"article","og_title":"ETL con Alteryx: Convertir XML a un set de datos relacionales","og_description":"ETL en Alteryx de un archivo XML, convirti\u00e9ndolo en un set de datos relacional, para facilitar su posterior consumo","og_url":"https:\/\/exceltic.serquo.com\/en\/creation-and-automation-of-an-etl-convert-xml-to-a-relational-dataset\/","article_publisher":"https:\/\/www.facebook.com\/exceltic\/","article_published_time":"2022-07-26T08:17:04+00:00","article_modified_time":"2022-10-27T07:05:37+00:00","og_image":[{"width":2560,"height":1449,"url":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2022\/07\/ETL-XML-min-scaled.webp","type":"image\/webp"}],"author":"Serquo Admin","twitter_card":"summary_large_image","twitter_creator":"@exceltic","twitter_site":"@exceltic","twitter_misc":{"Written by":"Serquo Admin","Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exceltic.serquo.com\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\/#article","isPartOf":{"@id":"https:\/\/exceltic.serquo.com\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\/"},"author":{"name":"Serquo Admin","@id":"https:\/\/exceltic.serquo.com\/#\/schema\/person\/aa4f97f58379cc64179590f276472ad5"},"headline":"ETL con Alteryx: Convertir XML a un set de datos relacionales","datePublished":"2022-07-26T08:17:04+00:00","dateModified":"2022-10-27T07:05:37+00:00","mainEntityOfPage":{"@id":"https:\/\/exceltic.serquo.com\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\/"},"wordCount":1351,"image":{"@id":"https:\/\/exceltic.serquo.com\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2022\/07\/ETL-XML-min-scaled.webp","articleSection":["Partners"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/exceltic.serquo.com\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\/","url":"https:\/\/exceltic.serquo.com\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\/","name":"ETL with Alteryx: Converting XML to a relational dataset","isPartOf":{"@id":"https:\/\/exceltic.serquo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exceltic.serquo.com\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\/#primaryimage"},"image":{"@id":"https:\/\/exceltic.serquo.com\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2022\/07\/ETL-XML-min-scaled.webp","datePublished":"2022-07-26T08:17:04+00:00","dateModified":"2022-10-27T07:05:37+00:00","author":{"@id":"https:\/\/exceltic.serquo.com\/#\/schema\/person\/aa4f97f58379cc64179590f276472ad5"},"description":"ETL in Alteryx of an XML file, converting it into a relational dataset, to facilitate its further consumption.","breadcrumb":{"@id":"https:\/\/exceltic.serquo.com\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exceltic.serquo.com\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/exceltic.serquo.com\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\/#primaryimage","url":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2022\/07\/ETL-XML-min-scaled.webp","contentUrl":"https:\/\/exceltic.serquo.com\/wp-content\/uploads\/2022\/07\/ETL-XML-min-scaled.webp","width":2560,"height":1449,"caption":"ETL"},{"@type":"BreadcrumbList","@id":"https:\/\/exceltic.serquo.com\/creacion-y-automatizacion-de-una-etl-convertir-xml-a-un-set-de-datos-relacionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exceltic.serquo.com\/"},{"@type":"ListItem","position":2,"name":"ETL con Alteryx: Convertir XML a un set de datos relacionales"}]},{"@type":"WebSite","@id":"https:\/\/exceltic.serquo.com\/#website","url":"https:\/\/exceltic.serquo.com\/","name":"","description":"Engineering and Consulting","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exceltic.serquo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/exceltic.serquo.com\/#\/schema\/person\/aa4f97f58379cc64179590f276472ad5","name":"Serquo Admin","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/c335bd9da7b1e9a671364c54e17ba39cb4a646b8eb953383973649c257b1fe49?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c335bd9da7b1e9a671364c54e17ba39cb4a646b8eb953383973649c257b1fe49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c335bd9da7b1e9a671364c54e17ba39cb4a646b8eb953383973649c257b1fe49?s=96&d=mm&r=g","caption":"Serquo Admin"},"url":"https:\/\/exceltic.serquo.com\/en\/author\/serquo\/"}]}},"_links":{"self":[{"href":"https:\/\/exceltic.serquo.com\/en\/wp-json\/wp\/v2\/posts\/1975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exceltic.serquo.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exceltic.serquo.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exceltic.serquo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exceltic.serquo.com\/en\/wp-json\/wp\/v2\/comments?post=1975"}],"version-history":[{"count":16,"href":"https:\/\/exceltic.serquo.com\/en\/wp-json\/wp\/v2\/posts\/1975\/revisions"}],"predecessor-version":[{"id":2287,"href":"https:\/\/exceltic.serquo.com\/en\/wp-json\/wp\/v2\/posts\/1975\/revisions\/2287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exceltic.serquo.com\/en\/wp-json\/wp\/v2\/media\/2008"}],"wp:attachment":[{"href":"https:\/\/exceltic.serquo.com\/en\/wp-json\/wp\/v2\/media?parent=1975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exceltic.serquo.com\/en\/wp-json\/wp\/v2\/categories?post=1975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exceltic.serquo.com\/en\/wp-json\/wp\/v2\/tags?post=1975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}